{"id":1531,"date":"2019-11-15T08:00:02","date_gmt":"2019-11-15T08:00:02","guid":{"rendered":"http:\/\/ebakislicer.com\/2019\/11\/15\/process-expo-2019\/"},"modified":"2020-06-09T15:50:49","modified_gmt":"2020-06-09T15:50:49","slug":"process-expo-2019","status":"publish","type":"post","link":"https:\/\/ebakislicer.com\/pt-br\/2019\/11\/15\/process-expo-2019\/","title":{"rendered":"Process Expo 2019"},"content":{"rendered":"<p>A PROCESS EXPO, celebrada no passado m\u00eas de outubro, \u00e9 a maior feira do pa\u00eds dedicada a trazer tecnologia de ponta e solu\u00e7\u00f5es integradas para todos os segmentos da ind\u00fastria de processamento e embalagem de alimentos e bebidas.<\/p>\n<p>Em mais uma edi\u00e7\u00e3o nosso representante nos EUA, a empresa ROSS, esteve presente com um grande stand, onde apresentou v\u00e1rias m\u00e1quinas, entre elas, o cortador horizontal EBAKI.<\/p>\n<p>Ross \u00e9 conhecido pela sua ampla gama de solu\u00e7\u00f5es de processamento e embalagem, incluindo sua linha de amaciadores de carne, sistemas de interven\u00e7\u00e3o antimicrobianos, equipamentos para resfriar e congelar, formadoras e prensas, cortadores, moedores e uma gama de equipamentos de seladora de bandejas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A PROCESS EXPO, celebrada no passado m\u00eas de outubro, \u00e9 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1521,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[69],"tags":[72,73,78,77],"class_list":["post-1531","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-maquinaria-de-alimentacao","tag-ebaki-pt-br","tag-feira","tag-filetera-horizontal-pt-br","tag-process-expo-pt-br"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Process Expo 2019 - EBAKI Fileteadora Industrial de Pollo y Carne | Cortadora Horizontal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ebakislicer.com\/pt-br\/2019\/11\/15\/process-expo-2019\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Process Expo 2019 - EBAKI Fileteadora Industrial de Pollo y Carne | Cortadora Horizontal\" \/>\n<meta property=\"og:description\" content=\"A PROCESS EXPO, celebrada no passado m\u00eas de outubro, \u00e9 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ebakislicer.com\/pt-br\/2019\/11\/15\/process-expo-2019\/\" \/>\n<meta property=\"og:site_name\" content=\"EBAKI Fileteadora Industrial de Pollo y Carne | Cortadora Horizontal\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-15T08:00:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-09T15:50:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ebakislicer.com\/wp-content\/uploads\/2019\/11\/cortadora-ebaki-process-expo2019.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"885\" \/>\n\t<meta property=\"og:image:height\" content=\"1180\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mila\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mila\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ebakislicer.com\\\/pt-br\\\/2019\\\/11\\\/15\\\/process-expo-2019\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ebakislicer.com\\\/pt-br\\\/2019\\\/11\\\/15\\\/process-expo-2019\\\/\"},\"author\":{\"name\":\"Mila\",\"@id\":\"https:\\\/\\\/ebakislicer.com\\\/#\\\/schema\\\/person\\\/fa1c44d6ef0eb49a86457fce0fa1dd16\"},\"headline\":\"Process Expo 2019\",\"datePublished\":\"2019-11-15T08:00:02+00:00\",\"dateModified\":\"2020-06-09T15:50:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ebakislicer.com\\\/pt-br\\\/2019\\\/11\\\/15\\\/process-expo-2019\\\/\"},\"wordCount\":117,\"publisher\":{\"@id\":\"https:\\\/\\\/ebakislicer.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/ebakislicer.com\\\/pt-br\\\/2019\\\/11\\\/15\\\/process-expo-2019\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ebakislicer.com\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/cortadora-ebaki-process-expo2019.jpg\",\"keywords\":[\"Ebaki\",\"feira\",\"Filetera horizontal\",\"Process Expo\"],\"articleSection\":[\"Maquinaria de alimenta\u00e7\u00e3o\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ebakislicer.com\\\/pt-br\\\/2019\\\/11\\\/15\\\/process-expo-2019\\\/\",\"url\":\"https:\\\/\\\/ebakislicer.com\\\/pt-br\\\/2019\\\/11\\\/15\\\/process-expo-2019\\\/\",\"name\":\"Process Expo 2019 - EBAKI Fileteadora Industrial de Pollo y Carne | Cortadora Horizontal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ebakislicer.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ebakislicer.com\\\/pt-br\\\/2019\\\/11\\\/15\\\/process-expo-2019\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ebakislicer.com\\\/pt-br\\\/2019\\\/11\\\/15\\\/process-expo-2019\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ebakislicer.com\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/cortadora-ebaki-process-expo2019.jpg\",\"datePublished\":\"2019-11-15T08:00:02+00:00\",\"dateModified\":\"2020-06-09T15:50:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ebakislicer.com\\\/pt-br\\\/2019\\\/11\\\/15\\\/process-expo-2019\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ebakislicer.com\\\/pt-br\\\/2019\\\/11\\\/15\\\/process-expo-2019\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/ebakislicer.com\\\/pt-br\\\/2019\\\/11\\\/15\\\/process-expo-2019\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ebakislicer.com\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/cortadora-ebaki-process-expo2019.jpg\",\"contentUrl\":\"https:\\\/\\\/ebakislicer.com\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/cortadora-ebaki-process-expo2019.jpg\",\"width\":885,\"height\":1180,\"caption\":\"Cortadora horizontal Ebaki en la feria Process Expo 2019\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ebakislicer.com\\\/pt-br\\\/2019\\\/11\\\/15\\\/process-expo-2019\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/ebakislicer.com\\\/pt-br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Process Expo 2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ebakislicer.com\\\/#website\",\"url\":\"https:\\\/\\\/ebakislicer.com\\\/\",\"name\":\"Ebakislicer - Fileteadora horizontal de carne\",\"description\":\"EBAKI: fileteadora industrial de pollo y carne sin hueso. Cortadora horizontal\",\"publisher\":{\"@id\":\"https:\\\/\\\/ebakislicer.com\\\/#organization\"},\"alternateName\":\"EBAKI \u2013 Fileteadora de pollo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ebakislicer.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ebakislicer.com\\\/#organization\",\"name\":\"Ebakislicer - Fileteadora horizontal de carne\",\"url\":\"https:\\\/\\\/ebakislicer.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/ebakislicer.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ebakislicer.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/EBAKI-logo.png\",\"contentUrl\":\"https:\\\/\\\/ebakislicer.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/EBAKI-logo.png\",\"width\":2362,\"height\":720,\"caption\":\"Ebakislicer - Fileteadora horizontal de carne\"},\"image\":{\"@id\":\"https:\\\/\\\/ebakislicer.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/dimaq.ebaki\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/dimaq-xxi-s-l\",\"https:\\\/\\\/www.youtube.com\\\/@DIMAQXXI\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ebakislicer.com\\\/#\\\/schema\\\/person\\\/fa1c44d6ef0eb49a86457fce0fa1dd16\",\"name\":\"Mila\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68fc130d14ef4894cfcbfc73b8194d8b5c904d3b4e41ad63f52e5a762fa9613c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68fc130d14ef4894cfcbfc73b8194d8b5c904d3b4e41ad63f52e5a762fa9613c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68fc130d14ef4894cfcbfc73b8194d8b5c904d3b4e41ad63f52e5a762fa9613c?s=96&d=mm&r=g\",\"caption\":\"Mila\"},\"url\":\"https:\\\/\\\/ebakislicer.com\\\/pt-br\\\/author\\\/mila\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Process Expo 2019 - EBAKI Fileteadora Industrial de Pollo y Carne | Cortadora Horizontal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ebakislicer.com\/pt-br\/2019\/11\/15\/process-expo-2019\/","og_locale":"pt_BR","og_type":"article","og_title":"Process Expo 2019 - EBAKI Fileteadora Industrial de Pollo y Carne | Cortadora Horizontal","og_description":"A PROCESS EXPO, celebrada no passado m\u00eas de outubro, \u00e9 [&hellip;]","og_url":"https:\/\/ebakislicer.com\/pt-br\/2019\/11\/15\/process-expo-2019\/","og_site_name":"EBAKI Fileteadora Industrial de Pollo y Carne | Cortadora Horizontal","article_published_time":"2019-11-15T08:00:02+00:00","article_modified_time":"2020-06-09T15:50:49+00:00","og_image":[{"width":885,"height":1180,"url":"https:\/\/ebakislicer.com\/wp-content\/uploads\/2019\/11\/cortadora-ebaki-process-expo2019.jpg","type":"image\/jpeg"}],"author":"Mila","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Mila","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ebakislicer.com\/pt-br\/2019\/11\/15\/process-expo-2019\/#article","isPartOf":{"@id":"https:\/\/ebakislicer.com\/pt-br\/2019\/11\/15\/process-expo-2019\/"},"author":{"name":"Mila","@id":"https:\/\/ebakislicer.com\/#\/schema\/person\/fa1c44d6ef0eb49a86457fce0fa1dd16"},"headline":"Process Expo 2019","datePublished":"2019-11-15T08:00:02+00:00","dateModified":"2020-06-09T15:50:49+00:00","mainEntityOfPage":{"@id":"https:\/\/ebakislicer.com\/pt-br\/2019\/11\/15\/process-expo-2019\/"},"wordCount":117,"publisher":{"@id":"https:\/\/ebakislicer.com\/#organization"},"image":{"@id":"https:\/\/ebakislicer.com\/pt-br\/2019\/11\/15\/process-expo-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/ebakislicer.com\/wp-content\/uploads\/2019\/11\/cortadora-ebaki-process-expo2019.jpg","keywords":["Ebaki","feira","Filetera horizontal","Process Expo"],"articleSection":["Maquinaria de alimenta\u00e7\u00e3o"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ebakislicer.com\/pt-br\/2019\/11\/15\/process-expo-2019\/","url":"https:\/\/ebakislicer.com\/pt-br\/2019\/11\/15\/process-expo-2019\/","name":"Process Expo 2019 - EBAKI Fileteadora Industrial de Pollo y Carne | Cortadora Horizontal","isPartOf":{"@id":"https:\/\/ebakislicer.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ebakislicer.com\/pt-br\/2019\/11\/15\/process-expo-2019\/#primaryimage"},"image":{"@id":"https:\/\/ebakislicer.com\/pt-br\/2019\/11\/15\/process-expo-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/ebakislicer.com\/wp-content\/uploads\/2019\/11\/cortadora-ebaki-process-expo2019.jpg","datePublished":"2019-11-15T08:00:02+00:00","dateModified":"2020-06-09T15:50:49+00:00","breadcrumb":{"@id":"https:\/\/ebakislicer.com\/pt-br\/2019\/11\/15\/process-expo-2019\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ebakislicer.com\/pt-br\/2019\/11\/15\/process-expo-2019\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ebakislicer.com\/pt-br\/2019\/11\/15\/process-expo-2019\/#primaryimage","url":"https:\/\/ebakislicer.com\/wp-content\/uploads\/2019\/11\/cortadora-ebaki-process-expo2019.jpg","contentUrl":"https:\/\/ebakislicer.com\/wp-content\/uploads\/2019\/11\/cortadora-ebaki-process-expo2019.jpg","width":885,"height":1180,"caption":"Cortadora horizontal Ebaki en la feria Process Expo 2019"},{"@type":"BreadcrumbList","@id":"https:\/\/ebakislicer.com\/pt-br\/2019\/11\/15\/process-expo-2019\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ebakislicer.com\/pt-br\/"},{"@type":"ListItem","position":2,"name":"Process Expo 2019"}]},{"@type":"WebSite","@id":"https:\/\/ebakislicer.com\/#website","url":"https:\/\/ebakislicer.com\/","name":"Ebakislicer - Fileteadora horizontal de carne","description":"EBAKI: fileteadora industrial de pollo y carne sin hueso. Cortadora horizontal","publisher":{"@id":"https:\/\/ebakislicer.com\/#organization"},"alternateName":"EBAKI \u2013 Fileteadora de pollo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ebakislicer.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ebakislicer.com\/#organization","name":"Ebakislicer - Fileteadora horizontal de carne","url":"https:\/\/ebakislicer.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ebakislicer.com\/#\/schema\/logo\/image\/","url":"https:\/\/ebakislicer.com\/wp-content\/uploads\/2025\/07\/EBAKI-logo.png","contentUrl":"https:\/\/ebakislicer.com\/wp-content\/uploads\/2025\/07\/EBAKI-logo.png","width":2362,"height":720,"caption":"Ebakislicer - Fileteadora horizontal de carne"},"image":{"@id":"https:\/\/ebakislicer.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/dimaq.ebaki\/","https:\/\/www.linkedin.com\/company\/dimaq-xxi-s-l","https:\/\/www.youtube.com\/@DIMAQXXI"]},{"@type":"Person","@id":"https:\/\/ebakislicer.com\/#\/schema\/person\/fa1c44d6ef0eb49a86457fce0fa1dd16","name":"Mila","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/68fc130d14ef4894cfcbfc73b8194d8b5c904d3b4e41ad63f52e5a762fa9613c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/68fc130d14ef4894cfcbfc73b8194d8b5c904d3b4e41ad63f52e5a762fa9613c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/68fc130d14ef4894cfcbfc73b8194d8b5c904d3b4e41ad63f52e5a762fa9613c?s=96&d=mm&r=g","caption":"Mila"},"url":"https:\/\/ebakislicer.com\/pt-br\/author\/mila\/"}]}},"_links":{"self":[{"href":"https:\/\/ebakislicer.com\/pt-br\/wp-json\/wp\/v2\/posts\/1531","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ebakislicer.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ebakislicer.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ebakislicer.com\/pt-br\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ebakislicer.com\/pt-br\/wp-json\/wp\/v2\/comments?post=1531"}],"version-history":[{"count":2,"href":"https:\/\/ebakislicer.com\/pt-br\/wp-json\/wp\/v2\/posts\/1531\/revisions"}],"predecessor-version":[{"id":1538,"href":"https:\/\/ebakislicer.com\/pt-br\/wp-json\/wp\/v2\/posts\/1531\/revisions\/1538"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ebakislicer.com\/pt-br\/wp-json\/wp\/v2\/media\/1521"}],"wp:attachment":[{"href":"https:\/\/ebakislicer.com\/pt-br\/wp-json\/wp\/v2\/media?parent=1531"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ebakislicer.com\/pt-br\/wp-json\/wp\/v2\/categories?post=1531"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ebakislicer.com\/pt-br\/wp-json\/wp\/v2\/tags?post=1531"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}